
{"id":36906,"date":"2026-05-12T15:20:31","date_gmt":"2026-05-12T18:20:31","guid":{"rendered":"https:\/\/visaodealagoas.com.br\/inicio\/?p=36906"},"modified":"2026-05-12T15:20:31","modified_gmt":"2026-05-12T18:20:31","slug":"banco-de-talentos-para-feira-negocio-da-grota-prorroga-inscricoes-interessados-podem-se-cadastrar-ate-o-dia-29-de-maio","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/banco-de-talentos-para-feira-negocio-da-grota-prorroga-inscricoes-interessados-podem-se-cadastrar-ate-o-dia-29-de-maio\/","title":{"rendered":"Banco de Talentos para Feira Neg\u00f3cio da Grota prorroga inscri\u00e7\u00f5es Interessados podem se cadastrar at\u00e9 o dia 29 de maio"},"content":{"rendered":"<p data-base-font=\"18\"><span data-base-font=\"18\">As inscri\u00e7\u00f5es para o novo Banco de Talentos da \u201cFeira Neg\u00f3cio da Grota\u201d foram prorrogadas. Agora, o cadastro pode ser realizado at\u00e9 o dia 29 de maio, \u00faltima sexta-feira do m\u00eas. O Banco de Talentos da Feira Neg\u00f3cio da Grota abre portas para que empreendedores das comunidades de Macei\u00f3 tenham a chance de ser convocados para edi\u00e7\u00f5es regulares e extraordin\u00e1rias da feira, al\u00e9m de eventos externos.<\/span><\/p>\n<p data-base-font=\"18\"><span data-base-font=\"18\">A Feira Neg\u00f3cio da Grota \u00e9 uma iniciativa do Instituto de Pesquisa, Planejamento e Licenciamento Urbano e Ambiental (Iplam), por meio da Diretoria Executiva de Inova\u00e7\u00e3o Urbana, Comunidades Urbanas e Urbanismo Social, que qualifica e d\u00e1 visibilidade a empreendimentos das comunidades urbanas.\u00a0<\/span><\/p>\n<p data-base-font=\"18\"><span data-base-font=\"18\">O projeto promove capacita\u00e7\u00f5es com os t\u00f3picos \u201cBoas Pr\u00e1ticas na Produ\u00e7\u00e3o de Alimentos&#8221;, &#8220;Ferramentas Digitais para o Empreendedorismo&#8221;, &#8220;Precifica\u00e7\u00e3o&#8221; e &#8220;Atendimento ao Cliente&#8221; que habilitam os participantes para as edi\u00e7\u00f5es do projeto.<\/span><\/p>\n<p data-base-font=\"18\"><span data-base-font=\"18\">Os interessados devem cumprir alguns requisitos, entre eles: residir h\u00e1 pelo menos tr\u00eas meses em comunidades urbanas, grotas, favelas ou \u00e1reas de vulnerabilidade social de Macei\u00f3, ter 18 anos completos ou ser maior de 16 anos (desde que apresente autoriza\u00e7\u00e3o expressa e por escrito do respons\u00e1vel legal, durante a inscri\u00e7\u00e3o).<\/span><\/p>\n<p data-base-font=\"18\"><span data-base-font=\"18\">Para a empreendedora Celiane G\u00f3es, o Neg\u00f3cio da Grota \u00e9 uma porta de entrada para possibilidades. \u201cParticipar dessa iniciativa foi uma virada de chave muito grande na minha vida e no meu neg\u00f3cio. Para mim, agregou muito, desde os primeiros momentos nas capacita\u00e7\u00f5es\u201d, destacou G\u00f3es.\u00a0<\/span><\/p>\n<p data-base-font=\"18\"><span data-base-font=\"18\">As inscri\u00e7\u00f5es s\u00e3o gratuitas. Para se cadastrar \u00e9 importante ler todas as diretrizes presentes no documento por meio do site:\u00a0<a href=\"https:\/\/www.diariomunicipal.com.br\/maceio\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-base-font=\"18\">https:\/\/www.diariomunicipal.com.br\/maceio\/<\/a><\/span>, acessar o site oficial do projeto pelo link:\u00a0<a href=\"https:\/\/negociodagrota.maceio.al.gov.br\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-base-font=\"18\"><span data-base-font=\"18\">https:\/\/negociodagrota.maceio.al.gov.br\/<\/span><\/a><span data-base-font=\"18\">, clicar no bot\u00e3o &#8220;INSCREVER-SE AGORA&#8221; e preencher o formul\u00e1rio com os dados solicitados. O cadastro tamb\u00e9m pode ser feito de maneira presencial no pr\u00e9dio do Iplam, localizado na rua Bar\u00e3o de Jaragu\u00e1, 398, no bairro do Jaragu\u00e1.\u00a0<\/span><\/p>\n<p data-base-font=\"18\">Fonte: Ascom Iplam<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As inscri\u00e7\u00f5es para o novo Banco de Talentos da \u201cFeira Neg\u00f3cio da Grota\u201d foram prorrogadas. Agora, o cadastro pode ser realizado at\u00e9 o dia 29 de maio, \u00faltima sexta-feira do m\u00eas. O Banco de Talentos da Feira Neg\u00f3cio da Grota abre portas para que empreendedores das comunidades de Macei\u00f3 tenham a chance de ser convocados &#8230;<\/p>\n","protected":false},"author":4,"featured_media":36907,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-36906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36906"}],"version-history":[{"count":1,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36906\/revisions"}],"predecessor-version":[{"id":36908,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36906\/revisions\/36908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/36907"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}