
{"id":36781,"date":"2026-05-04T15:50:51","date_gmt":"2026-05-04T18:50:51","guid":{"rendered":"https:\/\/visaodealagoas.com.br\/inicio\/?p=36781"},"modified":"2026-05-04T15:50:51","modified_gmt":"2026-05-04T18:50:51","slug":"educacao-de-maceio-convoca-escolas-para-participarem-da-eleicao-de-gremios-estudantis","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/educacao-de-maceio-convoca-escolas-para-participarem-da-eleicao-de-gremios-estudantis\/","title":{"rendered":"Educa\u00e7\u00e3o de Macei\u00f3 convoca escolas para participarem da elei\u00e7\u00e3o de gr\u00eamios estudantis"},"content":{"rendered":"<p><em>Regulamento com calend\u00e1rio eleitoral, campanha e organiza\u00e7\u00e3o das chapas foi publicado no Di\u00e1rio Oficial<\/em><\/p>\n<p data-base-font=\"18\">A rede p\u00fablica de educa\u00e7\u00e3o de Macei\u00f3 d\u00e1 mais um passo no fortalecimento da gest\u00e3o democr\u00e1tica e da participa\u00e7\u00e3o estudantil. Foi publicada, no Di\u00e1rio Oficial do Munic\u00edpio, desta segunda-feira (4), a convoca\u00e7\u00e3o das unidades escolares da segunda etapa do Ensino Fundamental (6\u00ba ao 9\u00ba ano), al\u00e9m da Educa\u00e7\u00e3o de Jovens, Adultos e Idosos (Ejai), para participarem da elei\u00e7\u00e3o dos Gr\u00eamios Estudantis.<\/p>\n<p data-base-font=\"18\">Ao todo, 20 escolas participam do processo. O pleito est\u00e1 previsto para ocorrer no dia 26 de maio e a posse est\u00e1 prevista para 2 de junho. O regulamento para a participa\u00e7\u00e3o no pleito, re\u00fane os objetivos da iniciativa, calend\u00e1rio eleitoral e as orienta\u00e7\u00f5es sobre a organiza\u00e7\u00e3o das chapas, campanha e vota\u00e7\u00e3o, al\u00e9m de detalhar o papel de cada participante no processo.<\/p>\n<p data-base-font=\"18\">A coordenadora-t\u00e9cnica de Articula\u00e7\u00e3o Escola, Fam\u00edlia e Comunidade da Semed, Edileuza Maciel, explica que a a\u00e7\u00e3o integra tr\u00eas eixos de atua\u00e7\u00e3o como os gr\u00eamios estudantis, os conselhos escolares &#8211; presentes em 144 unidades de ensino &#8211; e o Programa Escola Comunidade (Proec), vinculado ao Programa Dinheiro Direto na Escola (PDDE), que atende 48 escolas municipais.<\/p>\n<p data-base-font=\"18\">Segundo ela, o gr\u00eamio estudantil representa um avan\u00e7o importante para a rede p\u00fablica municipal de ensino. \u201cO aluno \u00e9 o principal usu\u00e1rio da educa\u00e7\u00e3o e precisa ter voz dentro da escola. O gr\u00eamio vem justamente com essa inten\u00e7\u00e3o que \u00e9 a de promover a participa\u00e7\u00e3o, discutir necessidades e contribuir com a gest\u00e3o escolar\u201d, destaca.<\/p>\n<p data-base-font=\"18\"><strong data-base-font=\"18\">Organiza\u00e7\u00e3o e participa\u00e7\u00e3o<\/strong><\/p>\n<p data-base-font=\"18\">O processo eleitoral ser\u00e1 conduzido dentro das pr\u00f3prias escolas, com apoio de um mediador escolhido em cada unidade educacional. Ainda de acordo com a coordenadora, os estudantes do 9\u00ba ano n\u00e3o poder\u00e3o se candidatar, mas atuar\u00e3o como organizadores da elei\u00e7\u00e3o, ao lado dos mediadores.<\/p>\n<p data-base-font=\"18\">Edileuza Maciel destaca que as chapas ser\u00e3o compostas para nove fun\u00e7\u00f5es, entre elas: presidente, vice-presidente, tesoureiro, secret\u00e1rio, diretor de cultura, diretor de esportes, diretor de comunica\u00e7\u00e3o e diretor de pol\u00edtica. Durante o per\u00edodo de campanha, os estudantes poder\u00e3o apresentar propostas por meio de cartazes, faixas e outras a\u00e7\u00f5es dentro das escolas.<\/p>\n<p data-base-font=\"18\">Al\u00e9m disso, o gr\u00eamio poder\u00e1 contar com recursos para desenvolver atividades, como eventos, palestras e a\u00e7\u00f5es culturais. Entre as iniciativas previstas est\u00e3o a valoriza\u00e7\u00e3o da cultura nordestina, com manifesta\u00e7\u00f5es como ciranda, coco de roda e outras express\u00f5es tradicionais.<\/p>\n<p data-base-font=\"18\"><strong data-base-font=\"18\">Forma\u00e7\u00e3o cidad\u00e3<\/strong><\/p>\n<p data-base-font=\"18\">Para a coordena\u00e7\u00e3o, o projeto vai al\u00e9m do ambiente escolar. \u201cO gr\u00eamio \u00e9 um espa\u00e7o de forma\u00e7\u00e3o cidad\u00e3. \u00c9 onde os estudantes come\u00e7am a entender seus direitos e deveres, exercem a democracia e desenvolvem lideran\u00e7a\u201d, afirma Edileuza.<\/p>\n<p data-base-font=\"18\">A coordenadora refor\u00e7a que equipes da Semed est\u00e3o visitando as escolas participantes para orientar estudantes, mediadores e chapas j\u00e1 formadas. &#8220;Em algumas unidades, como a Escola Manuel Pedro, h\u00e1 expectativa de m\u00faltiplas chapas concorrendo, o que refor\u00e7a o car\u00e1ter democr\u00e1tico da iniciativa\u201d, conclui.<\/p>\n<p data-base-font=\"18\">Fonte: Ascom Semed<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Regulamento com calend\u00e1rio eleitoral, campanha e organiza\u00e7\u00e3o das chapas foi publicado no Di\u00e1rio Oficial A rede p\u00fablica de educa\u00e7\u00e3o de Macei\u00f3 d\u00e1 mais um passo no fortalecimento da gest\u00e3o democr\u00e1tica e da participa\u00e7\u00e3o estudantil. Foi publicada, no Di\u00e1rio Oficial do Munic\u00edpio, desta segunda-feira (4), a convoca\u00e7\u00e3o das unidades escolares da segunda etapa do Ensino Fundamental &#8230;<\/p>\n","protected":false},"author":4,"featured_media":36782,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-36781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36781"}],"version-history":[{"count":1,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36781\/revisions"}],"predecessor-version":[{"id":36783,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36781\/revisions\/36783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/36782"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}