
{"id":36706,"date":"2026-04-29T20:20:01","date_gmt":"2026-04-29T23:20:01","guid":{"rendered":"https:\/\/visaodealagoas.com.br\/inicio\/?p=36706"},"modified":"2026-04-29T20:20:01","modified_gmt":"2026-04-29T23:20:01","slug":"hemoal-faz-coletas-externas-de-sangue-em-coruripe-e-penedo-nesta-quinta-feira","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/hemoal-faz-coletas-externas-de-sangue-em-coruripe-e-penedo-nesta-quinta-feira\/","title":{"rendered":"Hemoal faz coletas externas de sangue em Coruripe e Penedo nesta quinta-feira"},"content":{"rendered":"<h2 class=\"text-black font-18 mt-0 pt-0\">As a\u00e7\u00f5es ocorrem das 9h \u00e0s 16h, e visam facilitar o acesso dos moradores do Litoral Sul e Baixo S\u00e3o Francisco<\/h2>\n<p>O Hemocentro de Alagoas (Hemoal) encerra o m\u00eas de abril com duas coletas externas de sangue, que ser\u00e3o realizadas nesta quinta-feira (30). As a\u00e7\u00f5es itinerantes ir\u00e3o ocorrer das 9h \u00e0s 16h, na Unidade de Coleta e Transfus\u00e3o (UCT) de Coruripe, no bairro T\u00e9rcio Wanderley, bem como, na Santa Casa de Penedo, no Centro Hist\u00f3rico.<\/p>\n<p>&nbsp;<\/p>\n<p>Com meio das coletas externas, o Hemoal vai formar estoque estrat\u00e9gico de sangue para o Feriad\u00e3o de Tiradentes, que ocorre de sexta-feira (1\u00ba) at\u00e9 o domingo (3). Com isso, o hemocentro alagoano poder\u00e1 atender a demanda\u00a0transfusional das maternidades e hospitais alagoanos.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cCom o Programa\u00a0Hemoal\u00a0no Seu Munic\u00edpio, levaremos, nesta quinta-feira, nossas equipes itinerantes para Coruripe e Penedo. Deste modo, oportunizamos aos moradores do Litoral Sul e do Baixo S\u00e3o Francisco, a oportunidade de doarem sangue sem precisar se deslocar a Arapiraca e Macei\u00f3&#8221;, enfatizou o\u00a0assistente social do\u00a0Hemoal, Danilo Lima.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Quem pode doar<\/b><\/p>\n<p>As pessoas interessadas em doar sangue devem ter boa sa\u00fade, no m\u00ednimo 16 anos de idade e 50 quilos ou mais.\u00a0\u00c9 necess\u00e1rio, tamb\u00e9m, apresentar um documento de identifica\u00e7\u00e3o oficial e original com foto para se candidatar \u00e0 doa\u00e7\u00e3o de sangue.<\/p>\n<p>&nbsp;<\/p>\n<p>No caso das pessoas que se infectaram com o v\u00edrus da hepatite ap\u00f3s os 11 anos de idade, a proibi\u00e7\u00e3o de doar sangue \u00e9 permanente. A proibi\u00e7\u00e3o atinge os volunt\u00e1rios acometidos por\u00a0HIV, s\u00edfilis e doen\u00e7a de Chagas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Com rela\u00e7\u00e3o ao volunt\u00e1rio que fez tatuagem, maquiagem definitiva ou micropigmenta\u00e7\u00e3o, inclusive \u00e0quele que colocou piercing, a proibi\u00e7\u00e3o de doar sangue ocorre por um ano. Quanto ao doador que estiver gripado, com Influenza ou Covid-19, \u00e9 necess\u00e1rio aguardar 10 dias ap\u00f3s o fim dos sintomas para se candidatar \u00e0 doa\u00e7\u00e3o volunt\u00e1ria de sangue.<\/p>\n<p>Fonte: Ag\u00eancia Alagoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As a\u00e7\u00f5es ocorrem das 9h \u00e0s 16h, e visam facilitar o acesso dos moradores do Litoral Sul e Baixo S\u00e3o Francisco O Hemocentro de Alagoas (Hemoal) encerra o m\u00eas de abril com duas coletas externas de sangue, que ser\u00e3o realizadas nesta quinta-feira (30). As a\u00e7\u00f5es itinerantes ir\u00e3o ocorrer das 9h \u00e0s 16h, na Unidade de &#8230;<\/p>\n","protected":false},"author":4,"featured_media":36707,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-36706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36706"}],"version-history":[{"count":1,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36706\/revisions"}],"predecessor-version":[{"id":36708,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36706\/revisions\/36708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/36707"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}