
{"id":36614,"date":"2026-04-27T17:23:13","date_gmt":"2026-04-27T20:23:13","guid":{"rendered":"https:\/\/visaodealagoas.com.br\/inicio\/?p=36614"},"modified":"2026-04-27T17:23:13","modified_gmt":"2026-04-27T20:23:13","slug":"governo-de-alagoas-lanca-publicacao-caminhos-de-alagoas-nesta-terca-feira","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/governo-de-alagoas-lanca-publicacao-caminhos-de-alagoas-nesta-terca-feira\/","title":{"rendered":"Governo de Alagoas lan\u00e7a publica\u00e7\u00e3o Caminhos de Alagoas, nesta ter\u00e7a-feira"},"content":{"rendered":"<h2 class=\"text-black font-42 mb-0 pb-0 mt-0 pt-0   font-weight-900 font-xs-20 \">Governo de Alagoas lan\u00e7a publica\u00e7\u00e3o Caminhos de Alagoas, nesta ter\u00e7a-feira<\/h2>\n<p>O Governo de Alagoas lan\u00e7a nesta ter\u00e7a-feira (28), \u00e0s 9h, no Centro de Inova\u00e7\u00e3o do Jaragu\u00e1, em Macei\u00f3, \u00a0a primeira edi\u00e7\u00e3o do livro Caminhos de Alagoas. A obra assinada pela Secretaria de Estado do Planejamento, Gest\u00e3o e Patrim\u00f4nio (Seplag), traz uma an\u00e1lise de dados do estado e apresenta a influ\u00eancia dos programas p\u00fablicos estaduais no desenvolvimento de Alagoas.<\/p>\n<p>&nbsp;<\/p>\n<p>O livro com quase 300 p\u00e1ginas surgiu a partir da publica\u00e7\u00e3o Alagoas em Mapas, trazendo como diferencial, al\u00e9m dos mapas, as an\u00e1lises de dados elaboradas pela equipe da Superintend\u00eancia de Informa\u00e7\u00f5es e Cen\u00e1rios da Seplag (SINC\/Seplag), a apresenta\u00e7\u00e3o de programas do Governo de Alagoas e sua rela\u00e7\u00e3o com esses dados, v\u00e1rios gr\u00e1ficos e as expedi\u00e7\u00f5es de campo para registros fotogr\u00e1ficos.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante o lan\u00e7amento, haver\u00e1 apresenta\u00e7\u00e3o cultural com coco de roda e outros folguedos, al\u00e9m de fala institucional sobre a obra. Tamb\u00e9m ser\u00e1 realizada a entrega simb\u00f3lica de exemplares \u00e0 Universidade Federal de Alagoas (Ufal), \u00e0 Universidade Estadual de Alagoas (Uneal), \u00e0s bibliotecas p\u00fablicas do estado, \u00e0 Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa do Estado de Alagoas (Fapeal), ao Sebrae Alagoas e \u00e0 Casa da Ind\u00fastria Napole\u00e3o Barbosa.<\/p>\n<p>&nbsp;<\/p>\n<p>A programa\u00e7\u00e3o inclui ainda palestra sobre planejamento e gest\u00e3o p\u00fablica com a secret\u00e1ria de Estado da Fazenda, Renata Santos e sorteio de livros.<\/p>\n<p>&nbsp;<\/p>\n<p>O evento contar\u00e1 com a presen\u00e7a da secret\u00e1ria de Estado do Planejamento, Paula Dantas, do secret\u00e1rio especial de Planejamento, Or\u00e7amento e Governo Digital, Phelipe Vargas, entre outras autoridades estaduais.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Aviso de pauta<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Evento: Lan\u00e7amento do livro Caminhos de Alagoas<\/p>\n<p>Data: 28\/04\/2026<\/p>\n<p>Hor\u00e1rio: 9h<\/p>\n<p>&nbsp;<\/p>\n<p>Local: Centro de Inova\u00e7\u00e3o do Jaragu\u00e1<\/p>\n<p>Fonte: Ag\u00eancia Alagoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Governo de Alagoas lan\u00e7a publica\u00e7\u00e3o Caminhos de Alagoas, nesta ter\u00e7a-feira O Governo de Alagoas lan\u00e7a nesta ter\u00e7a-feira (28), \u00e0s 9h, no Centro de Inova\u00e7\u00e3o do Jaragu\u00e1, em Macei\u00f3, \u00a0a primeira edi\u00e7\u00e3o do livro Caminhos de Alagoas. A obra assinada pela Secretaria de Estado do Planejamento, Gest\u00e3o e Patrim\u00f4nio (Seplag), traz uma an\u00e1lise de dados do &#8230;<\/p>\n","protected":false},"author":4,"featured_media":36615,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-36614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoas"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36614"}],"version-history":[{"count":1,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36614\/revisions"}],"predecessor-version":[{"id":36616,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36614\/revisions\/36616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/36615"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}