
{"id":36564,"date":"2026-04-25T15:50:30","date_gmt":"2026-04-25T18:50:30","guid":{"rendered":"https:\/\/visaodealagoas.com.br\/inicio\/?p=36564"},"modified":"2026-04-25T15:50:30","modified_gmt":"2026-04-25T18:50:30","slug":"ima-al-promove-educacao-ambiental-na-semana-do-bioma-caatinga-em-delmiro-gouveia","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/ima-al-promove-educacao-ambiental-na-semana-do-bioma-caatinga-em-delmiro-gouveia\/","title":{"rendered":"IMA\/AL promove educa\u00e7\u00e3o ambiental na Semana do Bioma Caatinga, em Delmiro Gouveia"},"content":{"rendered":"<h2 class=\"text-black font-18 mt-0 pt-0\">Programa\u00e7\u00e3o conta com doa\u00e7\u00e3o e plantio de mudas nativas, al\u00e9m de palestras para estudantes da regi\u00e3o<\/h2>\n<p>O Instituto do Meio Ambiente de Alagoas (IMA\/AL) participa da Semana do Bioma Caatinga em Delmiro Gouveia. As atividades, que foram iniciadas na quarta-feira (22) e seguiram at\u00e9 esta sexta-feira (24), tiveram como objetivo promover conscientiza\u00e7\u00e3o e valoriza\u00e7\u00e3o deste bioma essencial para a biodiversidade alagoana.<\/p>\n<p>&nbsp;<\/p>\n<p>Na quarta, o \u00f3rg\u00e3o promoveu uma blitz ambiental com distribui\u00e7\u00e3o de mudas nativas para a popula\u00e7\u00e3o que compareceu ao centro da cidade, al\u00e9m do incentivo \u00e0 pr\u00e1ticas sustent\u00e1veis e cuidado com o meio ambiente. A a\u00e7\u00e3o foi realizada em parceria com a\u00a0Secretaria Municipal de Meio Ambiente de Delmiro Gouveia.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Buscamos fortalecer o di\u00e1logo com a sociedade atrav\u00e9s de a\u00e7\u00f5es educativas, plantio de mudas nativas, atividades de conscientiza\u00e7\u00e3o e mobiliza\u00e7\u00e3o social, aproximando a popula\u00e7\u00e3o da import\u00e2ncia da Caatinga para o equil\u00edbrio ambiental e a qualidade de vida&#8221;, disse o gerente de Educa\u00e7\u00e3o Ambiental, Ykson Emery.<\/p>\n<p>&nbsp;<\/p>\n<p>Nesta quinta-feira, foi realizado um plantio de mudas nativas na Usina Fotovoltaica do Tribunal de Justi\u00e7a de Alagoas (TJAL), com a participa\u00e7\u00e3o de servidores do TJAL e do Movimento Adolescentes e Crian\u00e7as (MAC).<\/p>\n<p>&nbsp;<\/p>\n<p>E na sexta-feira, os alunos da Escola Municipal Padre Anchieta, no Distrito Lagoinha, participam de diversas atividades de educa\u00e7\u00e3o ambiental, entre elas uma palestra sobre o papel do Macaco-prego na Caatinga.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cDurante todos esses anos, a secretaria, ao lado da gest\u00e3o municipal, tem realizado essas a\u00e7\u00f5es em parceria com o IMA, que sempre esteve conosco como um importante aliado nas iniciativas de educa\u00e7\u00e3o ambiental. Deixamos aqui o nosso reconhecimento e gratid\u00e3o por todo o apoio&#8221;, disse o secret\u00e1rio de Meio Ambiente de Delmiro Gouveia, Marco Diniz.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A Caatinga \u00e9 um bioma exclusivamente brasileiro, que ocupa 47,5% de todo o territ\u00f3rio alagoano e desempenha um papel fundamental na manuten\u00e7\u00e3o da biodiversidade e no equil\u00edbrio ecol\u00f3gico da regi\u00e3o. Celebrado no dia 28 de abril, o Dia da Caatinga surge como um momento de conscientiza\u00e7\u00e3o e mobiliza\u00e7\u00e3o, incentivando a responsabilidade ambiental de toda a sociedade e a import\u00e2ncia da preserva\u00e7\u00e3o desse patrim\u00f4nio natural.<\/p>\n<p>Fonte: Ag\u00eancia Alagoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa\u00e7\u00e3o conta com doa\u00e7\u00e3o e plantio de mudas nativas, al\u00e9m de palestras para estudantes da regi\u00e3o O Instituto do Meio Ambiente de Alagoas (IMA\/AL) participa da Semana do Bioma Caatinga em Delmiro Gouveia. As atividades, que foram iniciadas na quarta-feira (22) e seguiram at\u00e9 esta sexta-feira (24), tiveram como objetivo promover conscientiza\u00e7\u00e3o e valoriza\u00e7\u00e3o deste &#8230;<\/p>\n","protected":false},"author":4,"featured_media":36565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-36564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36564"}],"version-history":[{"count":1,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36564\/revisions"}],"predecessor-version":[{"id":36566,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36564\/revisions\/36566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/36565"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}