
{"id":33407,"date":"2025-12-15T11:08:19","date_gmt":"2025-12-15T14:08:19","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=33407"},"modified":"2025-12-15T11:08:19","modified_gmt":"2025-12-15T14:08:19","slug":"auxiliares-de-sala-ajudam-na-transformacao-da-educacao-infantil-na-rede-municipal","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/auxiliares-de-sala-ajudam-na-transformacao-da-educacao-infantil-na-rede-municipal\/","title":{"rendered":"Auxiliares de sala ajudam na transforma\u00e7\u00e3o da Educa\u00e7\u00e3o Infantil na rede municipal"},"content":{"rendered":"<p><em>Em parceria direta com professores, auxiliares comp\u00f5e equipe que sustenta as condi\u00e7\u00f5es necess\u00e1rias para o desenvolvimento infantil<\/em><\/p>\n<p data-base-font=\"18\">Os auxiliares de sala desempenham um papel fundamental na vida das crian\u00e7as desde os primeiros anos, atuando em parceria direta com o professor e contribuindo para o desenvolvimento dos pequenos estudantes da rede municipal de educa\u00e7\u00e3o de Macei\u00f3. Hoje, a Secretaria Municipal de Educa\u00e7\u00e3o(Semed) conta com cerca de 640 auxiliares de sala, distribu\u00eddos em 63 Centros Municipais de Educa\u00e7\u00e3o Infantil(CMEIs) e 13 escolas de Ensino Fundamental que ofertam esta etapa da educa\u00e7\u00e3o b\u00e1sica.<\/p>\n<p data-base-font=\"18\">A presen\u00e7a di\u00e1ria desses profissionais, que realizam acolhimentos, cuidam e educam ao longo de todo o ano, garante um ambiente acolhedor, organizado e prop\u00edcio \u00e0 aprendizagem, assegurando que cada crian\u00e7a seja ouvida, respeitada e estimulada a desenvolver plenamente suas capacidades. Mais do que apoiar rotinas, eles fazem parte do processo educativo, promovendo seguran\u00e7a afetiva, ampliando experi\u00eancias e fortalecendo v\u00ednculos essenciais para o crescimento integral das crian\u00e7as.<\/p>\n<p data-base-font=\"18\">A coordenadora de Educa\u00e7\u00e3o Infantil da Semed, Thainy Lira, destaca que o trabalho do auxiliar \u00e9 indissoci\u00e1vel do ato de educar. \u201cFalar do trabalho do auxiliar na Educa\u00e7\u00e3o Infantil \u00e9 reconhecer que cuidar e educar s\u00e3o dimens\u00f5es insepar\u00e1veis na pr\u00e1tica pedag\u00f3gica com crian\u00e7as, desde beb\u00eas\u201d, afirma.<\/p>\n<p data-base-font=\"18\">Segundo ela, esses profissionais atuam em parceria direta com o professor de refer\u00eancia, \u201ccompondo uma equipe que sustenta, no cotidiano, as condi\u00e7\u00f5es necess\u00e1rias para que cada crian\u00e7a viva e se desenvolva integralmente\u201d, complementa.<\/p>\n<p data-base-font=\"18\">Thainy refor\u00e7a que o papel do auxiliar vai muito al\u00e9m de a\u00e7\u00f5es operacionais. Ela explica que cada gesto de cuidado tamb\u00e9m educa, \u201cPois cada troca, cada acolhida, cada gesto de aten\u00e7\u00e3o comunica valores, promove seguran\u00e7a afetiva, possibilita v\u00ednculos e amplia experi\u00eancias\u201d.<\/p>\n<p data-base-font=\"18\">Para a coordenadora, reconhecer a import\u00e2ncia desses profissionais significa reconhecer que nenhum professor trabalha sozinho. \u201cA pot\u00eancia do fazer pedag\u00f3gico nasce da colabora\u00e7\u00e3o e do compromisso coletivo com uma educa\u00e7\u00e3o que respeita ritmos, necessidades e culturas infantis\u201d, frisa.<\/p>\n<p data-base-font=\"18\"><strong data-base-font=\"18\">Papel imprescind\u00edvel<\/strong><\/p>\n<p data-base-font=\"18\">A auxiliar de sala Mayrianne Souza de Alcantara Urtiga, que atua h\u00e1 14 anos na fun\u00e7\u00e3o e h\u00e1 3 anos como docente, conta que sua rotina envolve tanto o planejamento quanto a execu\u00e7\u00e3o das propostas pedag\u00f3gicas. No CMEI Graciliano Ramos, ela trabalha como professora no turno da manh\u00e3, com uma turma de 20 crian\u00e7as de 5 a 6 anos, e trabalha como auxiliar no turno vespertino, tamb\u00e9m com 20 crian\u00e7as, de 4 a 5 anos.<\/p>\n<p data-base-font=\"18\">\u201cNa fun\u00e7\u00e3o de auxiliar, tenho como atribui\u00e7\u00f5es, participar do planejamento pedag\u00f3gico, auxiliar as crian\u00e7as na execu\u00e7\u00e3o das propostas pedag\u00f3gicas, no cuidado de si, dos materiais e espa\u00e7os de uso coletivo e individual. Compreendo que o papel do auxiliar de sala \u00e9 imprescind\u00edvel para o planejamento, execu\u00e7\u00e3o, avalia\u00e7\u00e3o cont\u00ednua e acompanhamento do desenvolvimento integral das nossas crian\u00e7as\u201d, afirma.<\/p>\n<p data-base-font=\"18\">Mayrianne conta que o trabalho do auxiliar \u00e9 indispens\u00e1vel para o desenvolvimento integral dos pequenos. \u201cO papel do auxiliar de sala \u00e9 imprescind\u00edvel para o planejamento, execu\u00e7\u00e3o, avalia\u00e7\u00e3o cont\u00ednua e acompanhamento do desenvolvimento integral das nossas crian\u00e7as\u201d, diz.<\/p>\n<p data-base-font=\"18\">Segundo a auxiliar de sala, \u00e9 crucial uma forma\u00e7\u00e3o inicial e continuada, por atuar diretamente com as crian\u00e7as. \u201c\u00c9 importante entender o curr\u00edculo ampliado da rede, saber a concep\u00e7\u00e3o de crian\u00e7a e de educa\u00e7\u00e3o infantil e princialmente compreender que as nossas diretrizes o cuidar e o educar s\u00e3o indissoci\u00e1veis\u201d, destacou, acrescentando que faz parte da rotina preparar espa\u00e7os que convidem as crian\u00e7as \u00e0 participa\u00e7\u00e3o ativa, investigativa e explorat\u00f3ria, \u201cuma miss\u00e3o que exige do auxiliar de sala uma prepara\u00e7\u00e3o, organiza\u00e7\u00e3o e media\u00e7\u00e3o nas experi\u00eancias vividas pelas crian\u00e7as.\u201d<\/p>\n<p data-base-font=\"18\">Ela relata tamb\u00e9m os desafios e as recompensas do processo de adapta\u00e7\u00e3o. \u201cReceber nossas crian\u00e7as inseguras, chorosas, t\u00edmidas, muitas vezes em sua primeira experi\u00eancia escolar, \u00e9 sempre desafiador. Mas acompanhar sua evolu\u00e7\u00e3o \u00e9 muito prazeroso\u201d, afirma. Emocionada, Mayrianne lembra ainda das pequenas grandes conquistas que testemunha todos os dias: \u201cVer os olhos da crian\u00e7a brilhando ao conseguir construir suas produ\u00e7\u00f5es, realizar um reconto liter\u00e1rio ou vencer a timidez enche nosso cora\u00e7\u00e3o de afeto e de dever cumprido.\u201d<\/p>\n<p data-base-font=\"18\">\u201cAcompanhar o progresso das crian\u00e7as desde o primeiro tra\u00e7o at\u00e9 o final do ano letivo, com desenhos repletos de formas e representa\u00e7\u00f5es, \u00e9 um dos maiores presentes da profiss\u00e3o\u201d, finaliza.<\/p>\n<p data-base-font=\"18\">Fonte: Ascom Semed<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em parceria direta com professores, auxiliares comp\u00f5e equipe que sustenta as condi\u00e7\u00f5es necess\u00e1rias para o desenvolvimento infantil Os auxiliares de sala desempenham um papel fundamental na vida das crian\u00e7as desde os primeiros anos, atuando em parceria direta com o professor e contribuindo para o desenvolvimento dos pequenos estudantes da rede municipal de educa\u00e7\u00e3o de Macei\u00f3. &#8230;<\/p>\n","protected":false},"author":4,"featured_media":33408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-33407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33407"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/33408"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}