
{"id":32022,"date":"2025-08-20T15:03:49","date_gmt":"2025-08-20T18:03:49","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=32022"},"modified":"2025-08-20T15:03:49","modified_gmt":"2025-08-20T18:03:49","slug":"crescimento-da-malha-cicloviaria-transforma-orla-maritima-de-maceio-e-outros-pontos-da-cidade","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/crescimento-da-malha-cicloviaria-transforma-orla-maritima-de-maceio-e-outros-pontos-da-cidade\/","title":{"rendered":"Crescimento da malha ciclovi\u00e1ria transforma orla mar\u00edtima de Macei\u00f3 e outros pontos da cidade"},"content":{"rendered":"<p><em>Gest\u00e3o JHC amplia malha de 30 km para 96 km e incentiva lazer, esporte e deslocamento seguro \u00e0 beira-mar<\/em><\/p>\n<p data-base-font=\"18\">Desde o in\u00edcio da gest\u00e3o do prefeito JHC, em janeiro de 2021, a Prefeitura de Macei\u00f3 investe na mobilidade urbana da cidade com a amplia\u00e7\u00e3o dos espa\u00e7os destinados aos ciclistas. Para se ter uma ideia, a capital alagoana possu\u00eda apenas 30 km de ciclovias e ciclofaixas, naquele ano, e aumentou para uma malha de 96 km, em 2025, mais do que o dobro do planejamento inicial, agora com ciclorrotas, faixas verdes e passeio compartilhado.<\/p>\n<p data-base-font=\"18\">O avan\u00e7o reflete a estrat\u00e9gia de integrar os principais corredores urbanos da capital alagoana, conectando bairros e incentivando a ado\u00e7\u00e3o da bicicleta como meio de transporte seguro, sustent\u00e1vel e acess\u00edvel.<\/p>\n<p data-base-font=\"18\">Para o estudante universit\u00e1rio Luiz Eduardo Torres, morador de Ponta Verde, a ciclovia da orla mar\u00edtima tornou-se parte fundamental do seu dia a dia. Todos os finais de tarde, ele percorre os 4,5 km \u00e0 beira-mar, seja para pr\u00e1ticas esportivas, encontros com amigos ou pequenas compras no com\u00e9rcio local.<\/p>\n<p data-base-font=\"18\">\u201cPedalar na orla \u00e9 um al\u00edvio: o vento do mar, a seguran\u00e7a do espa\u00e7o demarcado e a aus\u00eancia de carros transformaram meu jeito de aproveitar a cidade. Antes, eu ficava mais tempo parado no tr\u00e2nsito ou dependente de \u00f4nibus; hoje, sigo tranquilo pela ciclovia, pratico exerc\u00edcio e chego onde preciso sem estresse\u201d, relata Luiz Eduardo.<\/p>\n<p data-base-font=\"18\">Al\u00e9m da orla mar\u00edtima, a gest\u00e3o JHC investiu em ciclovias de concreto e madeira na Avenida Fernandes Lima, ciclofaixas na Rota do Mar e outras interven\u00e7\u00f5es em avenidas como Durval de G\u00f3es Monteiro e Menino Marcelo.<\/p>\n<p data-base-font=\"18\">Segundo o Departamento Municipal de Transportes e Tr\u00e2nsito (DMTT), mais de 300 mil maceioenses utilizam a bicicleta como meio de transporte para o trabalho, estudo ou lazer, ajudando a descongestionar o tr\u00e2nsito, reduzir a emiss\u00e3o de poluentes e promover h\u00e1bitos mais saud\u00e1veis de vida na capital alagoana.<\/p>\n<p data-base-font=\"18\">Com planejamento cont\u00ednuo, a Prefeitura de Macei\u00f3 segue mapeando novos trechos priorit\u00e1rios, apostando na interliga\u00e7\u00e3o de ciclovias e ciclofaixas para criar um sistema ciclovi\u00e1rio cada vez mais abrangente e seguro.<\/p>\n<p data-base-font=\"18\">A perspectiva \u00e9 alcan\u00e7ar, nos pr\u00f3ximos anos, redes que atendam a todas as regi\u00f5es da cidade, consolidando a bicicleta como elemento-chave da mobilidade urbana local.<\/p>\n<p data-base-font=\"18\">Fonte: Secom Macei\u00f3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gest\u00e3o JHC amplia malha de 30 km para 96 km e incentiva lazer, esporte e deslocamento seguro \u00e0 beira-mar Desde o in\u00edcio da gest\u00e3o do prefeito JHC, em janeiro de 2021, a Prefeitura de Macei\u00f3 investe na mobilidade urbana da cidade com a amplia\u00e7\u00e3o dos espa\u00e7os destinados aos ciclistas. Para se ter uma ideia, a &#8230;<\/p>\n","protected":false},"author":4,"featured_media":32023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-32022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=32022"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/32023"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=32022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=32022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=32022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}