
{"id":30268,"date":"2025-02-04T19:14:29","date_gmt":"2025-02-04T22:14:29","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=30268"},"modified":"2025-02-04T19:14:29","modified_gmt":"2025-02-04T22:14:29","slug":"mais-agua-alagoas-redes-de-abastecimento-do-interior-vao-passar-por-manutencao-nos-proximos-dias","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/mais-agua-alagoas-redes-de-abastecimento-do-interior-vao-passar-por-manutencao-nos-proximos-dias\/","title":{"rendered":"Mais \u00c1gua Alagoas: redes de abastecimento do interior v\u00e3o passar por manuten\u00e7\u00e3o nos pr\u00f3ximos dias"},"content":{"rendered":"<h2 class=\"text-black font-18 mt-0 pt-0\">As obras da concession\u00e1ria \u00c1guas do Sert\u00e3o ser\u00e3o realizadas nas cidades de Igreja Nova, Penedo e S\u00e3o Miguel dos Campos<\/h2>\n<p>Mantendo o compromisso de melhorar o abastecimento de \u00e1gua nos munic\u00edpios atendidos, a concession\u00e1ria \u00c1guas do Sert\u00e3o vai realizar nos pr\u00f3ximos dias manuten\u00e7\u00f5es na rede de abastecimento em Igreja Nova, Penedo e S\u00e3o Miguel dos Campos. Em Igreja Nova, os trabalhos foram iniciados j\u00e1 nesta ter\u00e7a-feira (4), para melhoria no abastecimento do povoado Alagoinhas, e deve ser conclu\u00eddos ainda esta noite.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>No domingo (9), a Esta\u00e7\u00e3o de Tratamento de \u00c1gua (ETA) em Penedo passar\u00e1 por limpeza das 0h \u00e0s 4h, impactando o abastecimento na parte alta do munic\u00edpio. J\u00e1 na segunda-feira (10), em S\u00e3o Miguel dos Campos, a manuten\u00e7\u00e3o ser\u00e1 de responsabilidade da Equatorial Energia, das 8h30 \u00e0s 16h30, que deve afetar o fornecimento de \u00e1gua no bairro H\u00e9lio Jatob\u00e1 III.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Nas tr\u00eas cidades, a normaliza\u00e7\u00e3o do abastecimento deve acontecer horas ap\u00f3s a conclus\u00e3o dos trabalhos.<\/p>\n<p>De acordo com o secret\u00e1rio de Estado de Governo, Vitor Pereira, o trabalho de manuten\u00e7\u00e3o da rede de abastecimento de \u00e1gua \u00e9 fundamental para garantir que a popula\u00e7\u00e3o tenha acesso a um servi\u00e7o de qualidade e, principalmente, cont\u00ednuo. \u201cManter o abastecimento eficiente e com regularidade \u00e9 uma prioridade para o Governo de Alagoas, e estamos acompanhando de perto todas as a\u00e7\u00f5es realizadas, sempre em busca de melhorias para as comunidades atendidas. Nossa meta \u00e9 termos 100% dos munic\u00edpios atendidos pela empresa abastecidos de \u00e1gua pot\u00e1vel de qualidade at\u00e9 2027 e estamos de olho no cronograma para conseguirmos\u201d, destacou o secret\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>Os clientes que necessitarem de informa\u00e7\u00f5es adicionais sobre os trabalhos de manuten\u00e7\u00e3o podem entrar em contato diretamente com a equipe de atendimento da \u00c1guas do Sert\u00e3o, no 0800 000 2122 (por chamada de voz ou mensagens no WhatsApp), pelo site\u00a0<a href=\"http:\/\/www.aguasdosertao.com\/\" target=\"_blank\" rel=\"noopener\">www.aguasdosertao.com<\/a>, ou ainda pelo aplicativo da concession\u00e1ria, dispon\u00edvel para Android e iOS.<\/p>\n<p>&nbsp;<\/p>\n<p>Em caso de reclama\u00e7\u00f5es ou den\u00fancias sobre o servi\u00e7o prestado de qualquer concession\u00e1ria, seja de \u00e1gua ou energia el\u00e9trica, os usu\u00e1rios podem entrar em contato com a Ag\u00eancia Reguladora de Servi\u00e7os P\u00fablicos do Estado de Alagoas (Arsal), que fiscaliza o trabalho de todas as concession\u00e1rias do estado. A Ouvidoria da Arsal atende pelo WhatsApp no n\u00famero 82 98882-9707 ou pelo call center gratuito 0800 284 0429.<\/p>\n<p>Fonte: Ag\u00eancia Alagoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As obras da concession\u00e1ria \u00c1guas do Sert\u00e3o ser\u00e3o realizadas nas cidades de Igreja Nova, Penedo e S\u00e3o Miguel dos Campos Mantendo o compromisso de melhorar o abastecimento de \u00e1gua nos munic\u00edpios atendidos, a concession\u00e1ria \u00c1guas do Sert\u00e3o vai realizar nos pr\u00f3ximos dias manuten\u00e7\u00f5es na rede de abastecimento em Igreja Nova, Penedo e S\u00e3o Miguel dos &#8230;<\/p>\n","protected":false},"author":4,"featured_media":30269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-30268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/30268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=30268"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/30268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/30269"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=30268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=30268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=30268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}