
{"id":29243,"date":"2024-09-11T18:06:19","date_gmt":"2024-09-11T21:06:19","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=29243"},"modified":"2024-09-11T18:06:19","modified_gmt":"2024-09-11T21:06:19","slug":"mp-de-alagoas-e-mp-de-contas-reunem-prefeituras-de-maceio-e-arapiraca-para-apresentacao-do-painel-transparencia-dos-festejos-alagoanos","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/mp-de-alagoas-e-mp-de-contas-reunem-prefeituras-de-maceio-e-arapiraca-para-apresentacao-do-painel-transparencia-dos-festejos-alagoanos\/","title":{"rendered":"MP de Alagoas e MP de Contas re\u00fanem prefeituras de Macei\u00f3 e Arapiraca para apresenta\u00e7\u00e3o do Painel Transpar\u00eancia dos Festejos Alagoanos"},"content":{"rendered":"<p data-raofz=\"16\">Os gastos usando recursos p\u00fablicos para a realiza\u00e7\u00e3o de festividades nos munic\u00edpios alagoanos que t\u00eam sido frequentemente tema de discuss\u00f5es, provocou iniciativas dos \u00f3rg\u00e3os fiscalizadores. Nessa segunda-feira (9), o Minist\u00e9rio P\u00fablico de Alagoas (MPAL), por meio do N\u00facleo de Defesa do Patrim\u00f4nio (Nudepat) e o MP de Contas reuniram representantes do Poder Executivo de Arapiraca e de Macei\u00f3 para a apresenta\u00e7\u00e3o do Painel Transpar\u00eancia dos Festejos Alagoanos. Cada Munic\u00edpio realizar\u00e1 a alimenta\u00e7\u00e3o da ferramenta permitindo que a popula\u00e7\u00e3o tome ci\u00eancia, de forma mais clara e intuitiva, dos valores investidos.<\/p>\n<p data-raofz=\"16\">Essa n\u00e3o \u00e9 primeiro encontro para a apresenta\u00e7\u00e3o do painel. No dia 12 de agosto deste ano, na sede da Associa\u00e7\u00e3o dos Munic\u00edpios Alagoanos (AMA), a Procuradoria-Geral de Justi\u00e7a, o Nudepat, Tribunal de Contas do Estado e o MP de Contas fizeram a mesma apresenta\u00e7\u00e3o para representatividade dos 102 munic\u00edpios alagoanos.<\/p>\n<p data-raofz=\"16\">\u201cO painel \u00e9 uma ferramenta essencial que permitir\u00e1 maior transpar\u00eancia sobre contrata\u00e7\u00f5es de artistas e realiza\u00e7\u00e3o de eventos em nosso estado. Ele privilegiar\u00e1 um melhor controle preventivo, pois com o acesso \u00e0 informa\u00e7\u00e3o torna-se poss\u00edvel controlar os gastos, evitar superfaturamentos e ter um maior controle, inclusive social, em rela\u00e7\u00e3o aos eventos que<\/p>\n<p data-raofz=\"16\">sempre acontecem em todo Estado de Alagoas\u201d, explica o promotor de Justi\u00e7a do Nudepat, Bruno Baptista.<\/p>\n<p data-raofz=\"16\">Os dois munic\u00edpios foram convocados para uma reuni\u00e3o a parte por se tratar dos dois maiores de Alagoas e, evidentemente, com probabilidade de maior aporte de recursos p\u00fablicos para tal finalidade.<\/p>\n<p data-raofz=\"16\">\u201cEssa reuni\u00e3o se deu pela natural import\u00e2ncia que representam para o Estado. Seja pela capacidade financeira, seja pelo volume de eventos que realizam e o aporte de recursos em tais eventos\u201d, refor\u00e7a o promotor.<\/p>\n<p data-raofz=\"16\">Al\u00e9m da apresenta\u00e7\u00e3o do painel, durante a reuni\u00e3o foi pelos minist\u00e9rios P\u00fablico de Alagoas e de Contas que os munic\u00edpios indiquem representantes para a devida alimenta\u00e7\u00e3o da ferramenta. No entanto, para evitar expectativas antecipadas, vale ressaltar que a mesma ainda est\u00e1 em fase de alimenta\u00e7\u00e3o de dados para posteriormente ser lan\u00e7ada com acesso ao p\u00fablico em geral.<\/p>\n<p data-raofz=\"16\">Fonte: MPAL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os gastos usando recursos p\u00fablicos para a realiza\u00e7\u00e3o de festividades nos munic\u00edpios alagoanos que t\u00eam sido frequentemente tema de discuss\u00f5es, provocou iniciativas dos \u00f3rg\u00e3os fiscalizadores. Nessa segunda-feira (9), o Minist\u00e9rio P\u00fablico de Alagoas (MPAL), por meio do N\u00facleo de Defesa do Patrim\u00f4nio (Nudepat) e o MP de Contas reuniram representantes do Poder Executivo de Arapiraca &#8230;<\/p>\n","protected":false},"author":4,"featured_media":29244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-29243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/29243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=29243"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/29243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/29244"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=29243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=29243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=29243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}