
{"id":29175,"date":"2024-09-04T16:03:15","date_gmt":"2024-09-04T19:03:15","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=29175"},"modified":"2024-09-04T16:03:15","modified_gmt":"2024-09-04T19:03:15","slug":"o-secretario-de-estado-da-saude-gustavo-pontes-de-miranda-reforcou-que-todas-as-faixas-etarias-sao-igualmente-suscetiveis-a-doenca-ele-enfatizou-que-o-combate-ao-mosquito-aedes-aegypti-e-um-trabalh","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/o-secretario-de-estado-da-saude-gustavo-pontes-de-miranda-reforcou-que-todas-as-faixas-etarias-sao-igualmente-suscetiveis-a-doenca-ele-enfatizou-que-o-combate-ao-mosquito-aedes-aegypti-e-um-trabalh\/","title":{"rendered":"O secret\u00e1rio de Estado da Sa\u00fade, Gustavo Pontes de Miranda, refor\u00e7ou que todas as faixas et\u00e1rias s\u00e3o igualmente suscet\u00edveis \u00e0 doen\u00e7a. Ele enfatizou que o combate ao mosquito Aedes aegypti \u00e9 um trabalho coletivo que envolve toda popula\u00e7\u00e3o e os gestores municipais e que, por isso, diversas a\u00e7\u00f5es educativas foram realizadas este ano nos munic\u00edpios alagoanos.     \u201cDiante deste cen\u00e1rio epidemiol\u00f3gico n\u00e3o podemos baixar a guarda e continuaremos trabalhando ativamente nesta parceria colaborativa com os munic\u00edpios, prestando assist\u00eancia t\u00e9cnica, capacitando e realizando capacita\u00e7\u00f5es. Isso porque, os agentes de endemias municipais s\u00e3o os respons\u00e1veis por fazer a busca ativa dos focos do Aedes aegypti e de orientar a popula\u00e7\u00e3o quanto \u00e0 preven\u00e7\u00e3o\u201d, frisou o gestor da sa\u00fade estadual."},"content":{"rendered":"<h2 class=\"text-black font-18 mt-0 pt-0\">Competi\u00e7\u00e3o que leva o nome da craque alagoana acabou no \u00faltimo domingo<\/h2>\n<p>A Copa Rainha Marta acabou no \u00faltimo domingo ap\u00f3s a decis\u00e3o entre UDA e Canoense, mas segue rendendo grandes frutos. A maior atleta de futebol de todos os tempos, a alagoana de Dois Riachos, Marta Vieira, parabenizou as equipes participantes da competi\u00e7\u00e3o e agradeceu ao Governo Paulo Dantas pelo incentivo ao futebol feminino.<\/p>\n<p>&nbsp;<\/p>\n<p>Direto de Orlando, nos Estados Unidos, onde mora e joga pela equipe do Orlando Pride, a Rainha Marta deixou o seu recado, parabenizando equipes, atletas e o Estado pelo apoio.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cQuero aqui parabenizar as duas equipes finalistas e tamb\u00e9m a todas que participaram da competi\u00e7\u00e3o. Meu abra\u00e7o carinhoso tamb\u00e9m ao Governo do Estado, atrav\u00e9s da Secretaria do Esporte, Lazer e Juventude, que vem dando apoio \u00e0 modalidade. Tenho certeza que ano que vem ser\u00e1 ainda melhor. Espero estar a\u00ed presente para prestigiar mais uma final do campeonato\u201d, disse.<\/p>\n<p>&nbsp;<\/p>\n<p>A edi\u00e7\u00e3o 2024 da Copa Rainha Marta contou mais uma vez com 32 equipes, divididas entre Fase Interior e Fase Metropolitana, contando com 640 atletas inscritas.<\/p>\n<p>&nbsp;<\/p>\n<p>Maior competi\u00e7\u00e3o de futebol feminino de Alagoas, do Nordeste e uma das maiores do Brasil, diante do n\u00famero de equipes e estrutura oferecida, a Copa contou com um investimento de aproximadamente R$ 500 mil.<\/p>\n<p>&nbsp;<\/p>\n<p>Dentro desse aporte \u00e0 competi\u00e7\u00e3o, foram oferecidos uniformes personalizados para todos os times, apoio de transporte para as equipes do interior e premia\u00e7\u00f5es de medalhas, trof\u00e9us e financeira, com R$ 12 mil para a campe\u00e3 e R$ 6 mil para a vice.<\/p>\n<p>&nbsp;<\/p>\n<p>A secret\u00e1ria do Esporte, Lazer e Juventude, Lydia Pollyana, refor\u00e7ou o compromisso com o futebol feminino em Alagoas. \u201cO Governador Paulo Dantas defende que o apoio ao futebol feminino \u00e9 uma prioridade para a sua gest\u00e3o. Desde a realiza\u00e7\u00e3o da Copa Rainha Marta, at\u00e9 a concess\u00e3o de patroc\u00ednios para as equipes femininas, como a UDA e o Acau\u00e3, que disputam competi\u00e7\u00f5es nacionais, vamos seguir fortalecendo a modalidade e as atletas\u201d, afirmou.<\/p>\n<p><b>Proposta de abertura para equipes de outros estados<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>O apoio ao futebol feminino n\u00e3o para por a\u00ed. No \u00faltimo m\u00eas, a Secretaria do Esporte, Lazer e Juventude apresentou, durante a reuni\u00e3o do Cons\u00f3rcio Nordeste, na C\u00e2mara Tem\u00e1tica do Esporte, a proposta para regionalizar a disputa da Copa Rainha Marta, contando assim com a participa\u00e7\u00e3o dos nove estados do Nordeste.<\/p>\n<p>&nbsp;<\/p>\n<p>Na pr\u00f3xima reuni\u00e3o, ser\u00e1 discutida a ades\u00e3o dos estados e o formato da competi\u00e7\u00e3o, com previs\u00e3o de realiza\u00e7\u00e3o para 2025.<\/p>\n<p>Fonte: Ag\u00eancia Alagoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Competi\u00e7\u00e3o que leva o nome da craque alagoana acabou no \u00faltimo domingo A Copa Rainha Marta acabou no \u00faltimo domingo ap\u00f3s a decis\u00e3o entre UDA e Canoense, mas segue rendendo grandes frutos. A maior atleta de futebol de todos os tempos, a alagoana de Dois Riachos, Marta Vieira, parabenizou as equipes participantes da competi\u00e7\u00e3o e &#8230;<\/p>\n","protected":false},"author":4,"featured_media":29176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-29175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/29175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=29175"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/29175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/29176"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=29175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=29175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=29175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}