
{"id":28083,"date":"2024-05-15T13:52:07","date_gmt":"2024-05-15T16:52:07","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=28083"},"modified":"2024-05-15T13:52:07","modified_gmt":"2024-05-15T16:52:07","slug":"em-alagoas-seguranca-publica-avanca-contra-criminalidade-com-investimentos-em-mais-de-r-500-milhoes","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/em-alagoas-seguranca-publica-avanca-contra-criminalidade-com-investimentos-em-mais-de-r-500-milhoes\/","title":{"rendered":"Em Alagoas, Seguran\u00e7a P\u00fablica avan\u00e7a contra criminalidade com investimentos em mais de R$ 500 milh\u00f5es"},"content":{"rendered":"<h2 class=\"text-black font-18 mt-0 pt-0\">Nos \u00faltimos dois anos foram inaugurados 15 Centros Integrados e mais de 1.650 policiais foram nomeados para refor\u00e7ar as a\u00e7\u00f5es integradas<\/h2>\n<p>A Seguran\u00e7a P\u00fablica de Alagoas tem recebido cada vez mais investimentos para aumentar o combate \u00e0 criminalidade em todo o territ\u00f3rio do estado, conseguindo dados hist\u00f3ricos na redu\u00e7\u00e3o da viol\u00eancia. Nos \u00faltimos dois anos, no governo Paulo Dantas, houve a maior destina\u00e7\u00e3o de recursos para \u00e1rea com a inaugura\u00e7\u00e3o de Centros Integrados, delegacias e compras de equipamentos de alt\u00edssima qualidade internacional.<\/p>\n<p>&nbsp;<\/p>\n<p>Liderada pelo secret\u00e1rio Fl\u00e1vio Saraiva, a SSP-AL utilizou, de forma respons\u00e1vel, mais de R$ 510 milh\u00f5es, oriundos do Tesouro Estadual e do Fundo Nacional de Seguran\u00e7a P\u00fablica, para aquisi\u00e7\u00e3o de pistolas Glock; coletes bal\u00edsticos; viaturas blindadas; embarca\u00e7\u00f5es; instrumentos de menor potencial ofensivo; equipamentos e insumos para a Pol\u00edcia Cient\u00edfica; laborat\u00f3rio m\u00f3vel de per\u00edcia criminal; drones com vis\u00e3o termal; softwares para extra\u00e7\u00e3o de dados; escudos bal\u00edsticos; trajes antibomba para o Batalh\u00e3o de Opera\u00e7\u00f5es Policiais Especiais (Bope\/PM); quadriciclos; caminh\u00f5es tanques e autobombas; aeronaves e equipamentos de prote\u00e7\u00e3o individual como capacetes de combate a inc\u00eandio, para o Corpo de Bombeiros Militar, entre outros.<\/p>\n<p>&nbsp;<\/p>\n<p>Os investimentos, destaca o secret\u00e1rio, devem continuar sendo feitos para garantir a presta\u00e7\u00e3o de um servi\u00e7o que melhore a qualidade de vida das pessoas.<\/p>\n<p>\u201cTamb\u00e9m j\u00e1 compramos um helic\u00f3ptero multimiss\u00e3o H135, que \u00e9 de \u00faltima gera\u00e7\u00e3o e vai ajudar no socorro aerom\u00e9dico e nas atividades policiais que se fizerem necess\u00e1rias. A aeronave tamb\u00e9m \u00e9 preparada para utiliza\u00e7\u00e3o de \u00f3culos de vis\u00e3o noturna e vis\u00e3o sint\u00e9tica dos obst\u00e1culos, o que vai facilitar a captura de delinquentes. Em tudo o que compramos, fizemos comercializa\u00e7\u00f5es com uma economia m\u00e9dia de praticamente 50% em cima dos valores propostos no in\u00edcio dos processos licitat\u00f3rios. Gra\u00e7as a essa efici\u00eancia, que contou com o aux\u00edlio da Amgesp [Ag\u00eancia de Moderniza\u00e7\u00e3o da Gest\u00e3o de Processos], conseguiremos fazer mais investimentos para a \u00e1rea da seguran\u00e7a, que est\u00e1 recebendo a maior quantidade de recursos da hist\u00f3ria\u201d, afirma Fl\u00e1vio Saraiva.<\/p>\n<p><b>Novas unidades<\/b><\/p>\n<p>Al\u00e9m de equipamentos e meios de transporte destinados \u00e0s for\u00e7as de seguran\u00e7a e salvamento, o Governo de Alagoas inaugurou pr\u00e9dios p\u00fablicos que d\u00e3o mais conforto e qualidade de vida para o efetivo das institui\u00e7\u00f5es que integram a Seguran\u00e7a P\u00fablica.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre as entregas feitas, est\u00e3o 17 Centros Integrados de Seguran\u00e7a P\u00fablica, instalados em munic\u00edpios estrat\u00e9gicos que refor\u00e7am a atua\u00e7\u00e3o conjunta contra todo tipo de crime e contam ainda com as Salas Lil\u00e1s, para atendimento humanizado \u00e0s v\u00edtimas de viol\u00eancia dom\u00e9stica e aos vulner\u00e1veis.<\/p>\n<p>&nbsp;<\/p>\n<p>Dois Cisps tipo III receberam mais de R$ 32 milh\u00f5es para uma estrutura bem mais refor\u00e7ada e atualmente abrigam as sedes do Bope e da Diretoria de Repress\u00e3o \u00e0 Corrup\u00e7\u00e3o e ao Crime Organizado (Dracco\/PC). Outros dois Centros Integrados do tipo III est\u00e3o sendo constru\u00eddos em Santana do Ipanema e Uni\u00e3o dos Palmares e devem ser entregues no segundo semestre deste ano.<\/p>\n<p>Nos \u00faltimos dois anos, Alagoas tamb\u00e9m recebeu delegacias especializadas, como a de Crimes contra Vulner\u00e1veis, de Estelionato e o N\u00facleo de Atendimento \u00e0 Mulher, que funciona 24 horas no combate aos casos de viol\u00eancia dom\u00e9stica, familiar e sexual.<\/p>\n<p>&nbsp;<\/p>\n<p>Duas novas Centrais de Flagrantes foram inauguradas, melhorando o atendimento de registros de ocorr\u00eancia: uma unidade virtual, que \u00e9 a primeira do Nordeste, e a outra com um pr\u00e9dio moderno \u00e0s margens da Avenida Durval de G\u00f3es Monteiro, no Tabuleiro do Martins, em Macei\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m foram inauguradas as novas instala\u00e7\u00f5es do 3\u00ba Grupamento de Bombeiro Militar, em Uni\u00e3o dos Palmares; da Academia dos bombeiros em Arapiraca, que est\u00e1 realizando o 1\u00ba Curso de Forma\u00e7\u00e3o de Oficiais do estado; do Comando de Avia\u00e7\u00e3o do Estado, em Marechal Deodoro; do Aeroporto de Arapiraca e o Heliponto de Delmiro Gouveia.<\/p>\n<p>&nbsp;<\/p>\n<p>A Pol\u00edcia Cient\u00edfica ganhou postos de identifica\u00e7\u00e3o em mais munic\u00edpios do interior alagoano, como Traipu e Anadia, e a institucionaliza\u00e7\u00e3o da autonomia administrativa dos Institutos de Criminal\u00edstica do Agreste e Sert\u00e3o, al\u00e9m de inaugurar uma extens\u00e3o do Instituto M\u00e9dico Legal na Unidade de Emerg\u00eancia Dr. Daniel Houly visando atender v\u00edtimas de viol\u00eancia sexual com mais comodidade e facilidade. O Corpo de Bombeiros Militar tamb\u00e9m recebeu novos postos salva-vidas e a sede da Secretaria da Seguran\u00e7a P\u00fablica passa por reforma. O pr\u00e9dio tamb\u00e9m possui o novo Centro Integrado de Comando e Controle.<\/p>\n<p>&nbsp;<\/p>\n<p>Sobre a aplica\u00e7\u00e3o desses investimentos, o secret\u00e1rio Fl\u00e1vio Saraiva assegura que a aten\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o tem sido prioridade, al\u00e9m de valorizar o servidor.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cS\u00e3o estruturas novas que refor\u00e7am os cuidados do governo com seus profissionais e, claro, com o servi\u00e7o que \u00e9 prestado \u00e0 popula\u00e7\u00e3o. Temos lutado pela valoriza\u00e7\u00e3o do nosso efetivo para que possamos trabalhar com as melhores condi\u00e7\u00f5es poss\u00edveis. O resultado depende muito de como o trabalho \u00e9 feito e o desempenho das equipes precisa ter esse respaldo com equipamentos de qualidade e ambiente prop\u00edcio para o desenvolvimento das atividades\u201d, disse o secret\u00e1rio da Seguran\u00e7a P\u00fablica.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Qualifica\u00e7\u00e3o e refor\u00e7o<\/b><\/p>\n<p>As for\u00e7as de seguran\u00e7a e salvamento de Alagoas tamb\u00e9m t\u00eam ganhado refor\u00e7o no efetivo. No total, nos \u00faltimos dois anos, cerca de 1.700 policiais e bombeiros foram convocados pelo governo. Deste total, mais de 300 policiais civis e 120 policiais cient\u00edficos j\u00e1 est\u00e3o atuando nos diversos setores das institui\u00e7\u00f5es para as quais foram nomeados. Mil policiais militares e 148 bombeiros militares est\u00e3o concluindo o Curso de Forma\u00e7\u00e3o e, no final do m\u00eas ser\u00e3o formados para estarem efetivamente nas unidades das corpora\u00e7\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>Outros cerca de 80 policiais e bombeiros est\u00e3o no segundo ano do Curso de Forma\u00e7\u00e3o de Oficiais e em breve v\u00e3o estar aptos para refor\u00e7ar o efetivo nas ruas. O Estado tamb\u00e9m est\u00e1 promovendo um concurso para o preenchimento de cem vagas para o cargo de delegado da Pol\u00edcia Civil.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m da forma\u00e7\u00e3o de novos integrantes, a SSP tem promovido, junto com as institui\u00e7\u00f5es a ela vinculadas, diversas capacita\u00e7\u00f5es, como os cursos de Atendimento Pr\u00e9-Hospitalar T\u00e1tico (APH-T\u00e1tico), onde foi destinado R$ 1,2 milh\u00e3o, e os est\u00e1gios de Plano de Defesa, que tem recebido elogios do Governo Federal e vem sendo expandido para outros estados da federa\u00e7\u00e3o. Conforme o secret\u00e1rio Saraiva, as qualifica\u00e7\u00f5es tamb\u00e9m ajudam no desempenho das fun\u00e7\u00f5es diante das situa\u00e7\u00f5es do dia a dia.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEstamos preparando nosso efetivo para todo tipo de ocorr\u00eancia. Nos est\u00e1gios de plano de defesa, por exemplo, h\u00e1 habilita\u00e7\u00e3o para atua\u00e7\u00e3o em situa\u00e7\u00f5es de alta complexidade, alta intensidade e baixa familiaridade. Continuaremos mantendo os profissionais bem qualificados para que assim possamos obter os melhores atendimentos \u00e0 popula\u00e7\u00e3o, que \u00e9 quem mais ganha com isso\u201d, enalteceu o secret\u00e1rio da Seguran\u00e7a P\u00fablica.<\/p>\n<p><b>Opera\u00e7\u00f5es e parcerias<\/b><\/p>\n<p>Desde 2022, a SSP-AL tem fortalecido o trabalho integrado para combater as organiza\u00e7\u00f5es criminosas. No in\u00edcio da gest\u00e3o, foi criada uma for\u00e7a-tarefa de intelig\u00eancia com integrantes das for\u00e7as de seguran\u00e7a estaduais, que coordena a\u00e7\u00f5es, principalmente, contra foragidos da Justi\u00e7a.<\/p>\n<p>&nbsp;<\/p>\n<p>A SSP tamb\u00e9m formalizou parceria com \u00f3rg\u00e3os federais, como por exemplo, a cria\u00e7\u00e3o da For\u00e7a-tarefa Integrada de Combate ao Crime Organizado, que vem sendo desenvolvida em conjunto com as pol\u00edcias Federal e Rodovi\u00e1ria Federal e tamb\u00e9m com a Pol\u00edcia Penal, que pertencente \u00e0 Secretaria de Estado da Ressocializa\u00e7\u00e3o e Inclus\u00e3o Social.<\/p>\n<p>&nbsp;<\/p>\n<p>O secret\u00e1rio Fl\u00e1vio Saraiva celebra a uni\u00e3o de for\u00e7as pela garantia da tranquilidade do povo alagoano.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cAs a\u00e7\u00f5es integradas possibilitaram, por exemplo, a pris\u00e3o de Leandro Pinheiro de Barros, que matou a companheira em S\u00e3o Jos\u00e9 da Tapera. Ele foi encontrado com o aux\u00edlio de v\u00e1rios \u00f3rg\u00e3os como a Ag\u00eancia Brasileira de Intelig\u00eancia e a pol\u00edcia da Bol\u00edvia. Outras opera\u00e7\u00f5es tamb\u00e9m t\u00eam sido destaque como as pris\u00f5es dos envolvidos na chacina registrada em Arapiraca; de integrantes de torcidas organizadas envolvidos com crimes; teve a opera\u00e7\u00e3o Hades em v\u00e1rios estados do pa\u00eds com apreens\u00e3o at\u00e9 de aeronave que era usada no tr\u00e1fico de drogas. Ent\u00e3o, temos atuado no combate a todo tipo de crime\u201d, refor\u00e7ou.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m de a\u00e7\u00f5es repressivas, a SSP tem se destacado no trabalho preventivo. A chefia de Articula\u00e7\u00e3o de Pol\u00edticas de Preven\u00e7\u00e3o tem coordenado programas como o \u2018Na Base do Sossego\u2019, que j\u00e1 apreendeu mais de 400 equipamentos sonoros, e o \u2018Pessoa Idosa Protegida\u2019, em atua\u00e7\u00e3o conjunta com a Pol\u00edcia Militar, Corpo de Bombeiros Militar e outros \u00f3rg\u00e3os estaduais e municipais.<\/p>\n<p>Um olhar diferenciado tamb\u00e9m tem se voltado para reduzir a viol\u00eancia no ambiente escolar. A Chefia de Pol\u00edticas de Seguran\u00e7a \u00e0 Mulher ainda tem promovido a\u00e7\u00f5es de conscientiza\u00e7\u00e3o em favor deste p\u00fablico. O combate \u00e0 viol\u00eancia contra mulheres colocou Alagoas como o estado que mais reduz casos de feminic\u00eddio do Nordeste.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cA\u00e7\u00f5es pontuais que t\u00eam um efeito enorme em prol da seguran\u00e7a das pessoas. Com um trabalho conjunto, preventivo, ostensivo e repressivo estamos mudando a realidade de Alagoas\u201d, concluiu Fl\u00e1vio Saraiva.<\/p>\n<p>Fonte: Ag\u00eancia Alagoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos \u00faltimos dois anos foram inaugurados 15 Centros Integrados e mais de 1.650 policiais foram nomeados para refor\u00e7ar as a\u00e7\u00f5es integradas A Seguran\u00e7a P\u00fablica de Alagoas tem recebido cada vez mais investimentos para aumentar o combate \u00e0 criminalidade em todo o territ\u00f3rio do estado, conseguindo dados hist\u00f3ricos na redu\u00e7\u00e3o da viol\u00eancia. Nos \u00faltimos dois anos, &#8230;<\/p>\n","protected":false},"author":4,"featured_media":28086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-28083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoas"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/28083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=28083"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/28083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/28086"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=28083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=28083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=28083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}