
{"id":27642,"date":"2024-04-05T19:27:52","date_gmt":"2024-04-05T22:27:52","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=27642"},"modified":"2024-04-05T19:27:52","modified_gmt":"2024-04-05T22:27:52","slug":"estudantes-da-rede-estadual-participam-de-projeto-da-ufal-ifal-que-reune-jovens-prodigios-da-matematica","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/estudantes-da-rede-estadual-participam-de-projeto-da-ufal-ifal-que-reune-jovens-prodigios-da-matematica\/","title":{"rendered":"Estudantes da rede estadual participam de projeto da Ufal\/Ifal que re\u00fane jovens prod\u00edgios da Matem\u00e1tica"},"content":{"rendered":"<h2 class=\"text-black font-18 mt-0 pt-0\">Dezenove alunos de escolas estaduais foram selecionados para a turma 2024 do Novo Ensino Suplementar<\/h2>\n<p>Dezenove estudantes da rede estadual foram selecionados para a turma 2024 do Novo Ensino Suplementar (NES), projeto de extens\u00e3o do Instituto de Matem\u00e1tica da Universidade Federal Alagoas (Ufal) e do Instituto Federal de Alagoas (Ifal), que permite ao estudante do ensino m\u00e9dio ter acesso a conte\u00fados mais avan\u00e7ados em Matem\u00e1tica e Computa\u00e7\u00e3o, criando um centro de excel\u00eancia na forma\u00e7\u00e3o de talentos nessa \u00e1rea. Ao todo, 75 estudantes de Alagoas e demais estados brasileiros foram selecionados para o projeto.<\/p>\n<p>&nbsp;<\/p>\n<p>Dentre os 19 selecionados da rede estadual est\u00e3o alunos das escolas Manoel de Matos (Santana do Munda\u00fa); Fernandes Lima (Macei\u00f3); Alfredo Gaspar de Mendon\u00e7a (Macei\u00f3), Pedro Joaquim de Jesus (Teot\u00f4nio Vilela); Ana Lins (S\u00e3o Miguel dos Campos); Francisca Rosa da Costa (Delmiro Gouveia) e Col\u00e9gio Tiradentes da Pol\u00edcia Militar \u2013 Unidade Agreste (Arapiraca).<\/p>\n<p>O NES vai proporcionar aos estudantes uma forma\u00e7\u00e3o integral e inovadora, que abordar\u00e1 temas ligados \u00e0 Matem\u00e1tica, Ci\u00eancia de Dados e Intelig\u00eancia Artificial. As atividades acontecem de forma h\u00edbrida \u2013 presencial e online \u2013 e incluem ainda palestras e workshops com pesquisadores brasileiros e norte-americanos, curso de Ingl\u00eas, esportes e intera\u00e7\u00e3o com empresas.<\/p>\n<p>&nbsp;<\/p>\n<p>O curso ter\u00e1 dura\u00e7\u00e3o de tr\u00eas anos e, a cada ano, s\u00e3o cursados dois m\u00f3dulos. No primeiro ano, o estudante aprende sobre programa\u00e7\u00e3o; no segundo, aprofunda-se em Intelig\u00eancia Artificial e, por fim, no terceiro e \u00faltimo ano, estudar\u00e1 Ci\u00eancia de Dados. Ap\u00f3s a conclus\u00e3o de cada ano, o aluno recebe um certificado de conclus\u00e3o dos m\u00f3dulos.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEstamos iniciando o ano celebrando as conquistas de 2023 e recepcionando a turma que come\u00e7a em 2024 com excelentes expectativas para esta jornada\u201d, destacou Krerley Oliveira, professor do Instituto de Matem\u00e1tica e coordenador do projeto, durante a aula inaugural do NES, no audit\u00f3rio da Reitoria da Ufal, no Campus AC Sim\u00f5es.<\/p>\n<p>Representando a Secretaria de Estado da Educa\u00e7\u00e3o (Seduc) na aula inaugural, Nathally Marques, t\u00e9cnica da Ger\u00eancia de Desenvolvimento do Ensino M\u00e9dio elogiou a iniciativa e aconselhou os estudantes selecionados a aproveitarem ao m\u00e1ximo a experi\u00eancia. \u201cO Ensino M\u00e9dio \u00e9 uma etapa importante na vida de um jovem, pois \u00e9 uma fase de transi\u00e7\u00e3o para a vida adulta. Por isso, o estudante deve aproveitar ao m\u00e1ximo esta oportunidade de enriquecimento de aprendizado\u201d, disse Nathally.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Expectativas<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Aluno da Escola Estadual Firmo de Castro, de Porto Real do Col\u00e9gio, Jo\u00e3o Pedro Pacheco est\u00e1 em seu segundo ano no NES. Ele relata que o programa mudou sua vida e lhe mostrou novas possibilidades. \u201cCom o NES, percebi que posso fazer o que quiser: posso tentar um curso na FGV, posso fazer o Enem e tentar uma vaga em uma faculdade no exterior. Posso me reinventar a qualquer momento. O programa traz essas perspectivas e nos propicia experi\u00eancias que agregam n\u00e3o somente ao meu curr\u00edculo, mas a minha vida\u201d, observa.<\/p>\n<p>Alunas do Col\u00e9gio Tiradentes da Pol\u00edcia Militar &#8211; Unidade Agreste, de Arapiraca, Kawany Moreira e Claudia Manuelly Soares Santos foram selecionadas para a turma de 2024 e est\u00e3o animadas para o curso. \u201cMesmo estando ainda no 9\u00ba ano, estou ansiosa por aprender conte\u00fados mais avan\u00e7ados\u201d, contou Kawany. \u201cAcredito que o curso vai me proporcionar mais conhecimento e ser\u00e1 um propulsor para projetos futuros na minha vida\u201d, complementou Cl\u00e1udia.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Planos<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>De Santana do Munda\u00fa, as estudantes Allyce Ferreira e Jenyffer Mickaele tamb\u00e9m s\u00e3o estreantes no NES. Elas foram selecionadas quando ainda estavam no ensino fundamental da rede municipal e, agora, estudantes do ensino m\u00e9dio da Escola Estadual Manoel de Matos, fazem planos em rela\u00e7\u00e3o ao futuro.<\/p>\n<p>\u201cParticipamos do Polo Ol\u00edmpico do professor Valdemir em Santana do Munda\u00fa e isso foi essencial para sermos selecionadas. Quero aprender bastante no NES, principalmente na \u00e1rea de Computa\u00e7\u00e3o, pois quero empreender e abrir meu neg\u00f3cio, mas tamb\u00e9m prestar o Enem\u201d, adiantou Allyce. \u201cGosto de programa\u00e7\u00e3o e de jogos, e creio que o NES me abrir\u00e1 muitas portas\u201d, afirmou Jenyffer.<\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m aprovada para a turma de 2024, Mariana Lins, da Escola Estadual Fernandes Lima, de Macei\u00f3, almeja ajudar a sua comunidade. \u201cFiquei muito feliz por ter sido aprovada. Meu sonho \u00e9 me aprofundar em programa\u00e7\u00e3o, matem\u00e1tica e ser cientista de dados. Quero ajudar as pessoas ao meu redor\u201d, declarou a adolescente.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Parceiros e Financiadores<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>O NES tem como financiadores a empresa de servi\u00e7os financeiros e pagamentos eletr\u00f4nicos Stoneco, a Funda\u00e7\u00e3o Get\u00falio Vargas (FGV) e a parceria do grupo Etapa Educacional e do programa de imers\u00e3o em ci\u00eancia, tecnologia, engenharia e matem\u00e1tica americano Sigma Camp.<\/p>\n<p>Fonte: Ag\u00eancia Alagoas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dezenove alunos de escolas estaduais foram selecionados para a turma 2024 do Novo Ensino Suplementar Dezenove estudantes da rede estadual foram selecionados para a turma 2024 do Novo Ensino Suplementar (NES), projeto de extens\u00e3o do Instituto de Matem\u00e1tica da Universidade Federal Alagoas (Ufal) e do Instituto Federal de Alagoas (Ifal), que permite ao estudante do &#8230;<\/p>\n","protected":false},"author":4,"featured_media":27643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-27642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoas"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/27642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=27642"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/27642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/27643"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=27642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=27642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=27642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}