
{"id":16232,"date":"2021-12-21T14:59:47","date_gmt":"2021-12-21T17:59:47","guid":{"rendered":"http:\/\/visaodealagoas.com.br\/home\/?p=16232"},"modified":"2021-12-21T14:59:47","modified_gmt":"2021-12-21T17:59:47","slug":"requinte-de-beleza","status":"publish","type":"post","link":"https:\/\/visaodealagoas.com.br\/inicio\/requinte-de-beleza\/","title":{"rendered":"REQUINTE DE BELEZA"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><span class='vw-dropcap vw-dropcap-standard'>E<\/span> foi a\u00ed que a tarde come\u00e7ou a amorenar rapidamente, eu a passear sozinho quase n\u00e3o percebia o passar das horas e que diante de mim j\u00e1 iniciava a noite, de repente come\u00e7ou a descortinar no infinito mar um clar\u00e3o da lua, que cuidadosamente se levantava devagarinho, buscando entre as nuvens iluminar cada cantinho com sua luminosidade. De repente as arvores ficaram menos revoltantes e o mar acalmado, as embarca\u00e7\u00f5es balan\u00e7avam ritmicamente como um bailar e o vento ressoava em calmaria. Todo os acordes devidos n\u00e3o seguiriam tal entona\u00e7\u00f5es de momento, vez que a lua descortinando junto com o mar, nos brindava um bel\u00edssimo espet\u00e1culo livre, sem bilheteria nem ingresso e que seguiam ladeados harmonicamente como um casal sonhador. Que se doavam em cumplicidades de uma leveza quase impercept\u00edveis aos nossos olhos, transformando amistosamente jovens e adultos que eram espectadores desse lindo cen\u00e1rio, tamb\u00e9m em sonhadores casais.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: center;\"><em><b>Valter Lima<\/b><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E foi a\u00ed que a tarde come\u00e7ou a amorenar rapidamente, eu a passear sozinho quase n\u00e3o percebia o passar das horas e que diante de mim j\u00e1 iniciava a noite, de repente come\u00e7ou a descortinar no infinito mar um clar\u00e3o da lua, que cuidadosamente se levantava devagarinho, buscando entre as nuvens iluminar cada cantinho com &#8230;<\/p>\n","protected":false},"author":3,"featured_media":16233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-16232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visao-literaria"],"_links":{"self":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/16232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=16232"}],"version-history":[{"count":0,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/posts\/16232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media\/16233"}],"wp:attachment":[{"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=16232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=16232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visaodealagoas.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=16232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}